{"id":13002,"date":"2025-07-21T13:51:30","date_gmt":"2025-07-21T10:51:30","guid":{"rendered":"https:\/\/devboats.sales-readiness.eu\/cookie-policy-eu\/"},"modified":"2025-07-21T13:51:30","modified_gmt":"2025-07-21T10:51:30","slug":"cookie-policy-eu","status":"publish","type":"page","link":"https:\/\/arcticboats.eu\/fr\/cookie-policy-eu\/","title":{"rendered":"Cookie Policy (EU)"},"content":{"rendered":"\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Cette politique de cookies a \u00e9t\u00e9 mise \u00e0 jour pour la derni\u00e8re fois le 21 juillet 2025 et s\u2019applique aux citoyens et aux r\u00e9sidents permanents l\u00e9gaux de l\u2019Espace \u00c9conomique Europ\u00e9en et de la Suisse.<\/i><br><\/p><h2>1. Introduction<\/h2><p>Notre site web, <a href=\"https:\/\/arcticboats.eu\/fr\/\">https:\/\/arcticboats.eu\/fr\/<\/a> (ci-apr\u00e8s\u00a0: \u00ab\u00a0le site web\u00a0\u00bb) utilise des cookies et autres technologies li\u00e9es (par simplification, toutes ces technologies sont d\u00e9sign\u00e9es par le terme \u00ab\u00a0cookies\u00a0\u00bb). Des cookies sont \u00e9galement plac\u00e9s par des tierces parties que nous avons engag\u00e9es. Dans le document ci-dessous, nous vous informons de l\u2019utilisation des cookies sur notre site web.<\/p><h2>2. Que sont les cookies\u00a0?<\/h2><p>Un cookie est un petit fichier simple envoy\u00e9 avec les pages de ce site web et stock\u00e9 par votre navigateur sur le disque dur de votre ordinateur ou d\u2019un autre appareil. Les informations qui y sont stock\u00e9es peuvent \u00eatre renvoy\u00e9es \u00e0 nos serveurs ou aux serveurs des tierces parties concern\u00e9es lors d\u2019une visite ult\u00e9rieure.<\/p><h2>3. Que sont les scripts\u00a0?<\/h2><p>Un script est un \u00e9l\u00e9ment de code utilis\u00e9 pour que notre site web fonctionne correctement et de mani\u00e8re interactive. Ce code est ex\u00e9cut\u00e9 sur notre serveur ou sur votre appareil.<\/p><h2>4. Qu\u2019est-ce qu\u2019une balise invisible\u00a0?<\/h2><p>Une balise invisible (ou balise web) est un petit morceau de texte ou d\u2019image invisible sur un site web, utilis\u00e9 pour suivre le trafic sur un site web. Pour ce faire, diverses donn\u00e9es vous concernant sont stock\u00e9es \u00e0 l\u2019aide de balises invisibles.<\/p><h2>5. Cookies<\/h2><h3>5.1 Cookies techniques ou fonctionnels<\/h3><p>Certains cookies assurent le fonctionnement correct de certaines parties du site web et la prise en compte de vos pr\u00e9f\u00e9rences en tant qu\u2019internaute. En pla\u00e7ant des cookies fonctionnels, nous vous facilitons la visite de notre site web. Ainsi, vous n\u2019avez pas besoin de saisir \u00e0 plusieurs reprises les m\u00eames informations lors de la visite de notre site web et, par exemple, les \u00e9l\u00e9ments restent dans votre panier jusqu\u2019\u00e0 votre paiement. Nous pouvons d\u00e9poser ces cookies sans votre consentement.<\/p><h3>5.2 Cookies statistiques<\/h3><p>Nous utilisons des cookies statistiques afin d\u2019optimiser l\u2019exp\u00e9rience des internautes sur notre site web. Avec ces cookies statistiques, nous obtenons des informations sur l\u2019utilisation de notre site web.&nbsp;Nous demandons votre permission pour placer des cookies statistiques.<\/p><h3>5.3 Cookies de marketing\/suivi<\/h3><p>Les cookies de marketing\/suivi sont des cookies ou toute autre forme de stockage local, utilis\u00e9s pour cr\u00e9er des profils d\u2019utilisateurs afin d\u2019afficher de la publicit\u00e9 ou de suivre l\u2019utilisateur sur ce site web ou sur plusieurs sites web dans des finalit\u00e9s marketing similaires.<\/p><h3>5.4 R\u00e9seaux sociaux<\/h3><p>Sur notre site web, nous avons inclus du contenu provenant de Facebook, Instagram, X (Formerly Twitter) et LinkedIn pour promouvoir des pages web (par exemple, \u00ab\u00a0like\u00a0\u00bb, \u00ab\u00a0pin\u00a0\u00bb) ou les partager (par exemple, \u00ab\u00a0tweet\u00a0\u00bb) sur des r\u00e9seaux sociaux comme Facebook, Instagram, X (Formerly Twitter) et LinkedIn. Ce contenu est int\u00e9gr\u00e9 gr\u00e2ce un code obtenu de Facebook, Instagram, X (Formerly Twitter) et LinkedIn et place des cookies. Ce contenu peut stocker et traiter certaines informations \u00e0 des fins de publicit\u00e9 personnalis\u00e9e.<\/p><p>Veuillez lire la d\u00e9claration de confidentialit\u00e9 de ces r\u00e9seaux sociaux (qui peut \u00eatre modifi\u00e9e r\u00e9guli\u00e8rement) afin de savoir ce qu\u2019ils font de vos donn\u00e9es (personnelles) trait\u00e9es en utilisant ces cookies. Les donn\u00e9es r\u00e9cup\u00e9r\u00e9es sont anonymis\u00e9es autant que possible. Facebook, Instagram, X (Formerly Twitter) et LinkedIn se trouvent aux \u00c9tats-Unis.<\/p><h2>6. Cookies plac\u00e9s<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Functional<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service \" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons WordPress pour website development. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordpress\/\">En savoir plus sur WordPress<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp_preferences_user_\/\">WP_PREFERENCES_USER_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wpemojisettingssupports\/\">wpEmojiSettingsSupports<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings\/\">wp-settings-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings-time\/\">wp-settings-time-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">1 year<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_test_cookie\/\">wordpress_test_cookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_logged_in_\/\">wordpress_logged_in_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp_lang\/\">wp_lang<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WPML<\/h3>\n\t\t<p>Functional<\/p>\n\t\t<label for=\"cmplz_service_wpml\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wpml<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wpml\" class=\"cmplz-accept-service \" data-service=\"wpml\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons WPML pour locale management. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wpml\/\">En savoir plus sur WPML<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wpml\/wp-wpml_current_language\/\">wp-wpml_current_language<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">1 day<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Complianz<\/h3>\n\t\t<p>Functional<\/p>\n\t\t<label for=\"cmplz_service_complianz\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service complianz<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_complianz\" class=\"cmplz-accept-service \" data-service=\"complianz\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Complianz pour cookie consent management. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/complianz\/\">En savoir plus sur Complianz<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.&nbsp;Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/complianz.io\/legal\/privacy-statement\/\">d\u00e9claration de confidentialit\u00e9 Complianz<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_functional\/\">cmplz_functional<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_statistics\/\">cmplz_statistics<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_preferences\/\">cmplz_preferences<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_marketing\/\">cmplz_marketing<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_policy_id\/\">cmplz_policy_id<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_consented_services\/\">cmplz_consented_services<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_banner-status\/\">cmplz_banner-status<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/complianz\/cmplz_cookie_data\/\">cmplz_cookie_data<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">365 jours<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Burst Statistics<\/h3>\n\t\t<p>Statistics (anonymous)<\/p>\n\t\t<label for=\"cmplz_service_burst-statistics\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service burst-statistics<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_burst-statistics\" class=\"cmplz-accept-service \" data-service=\"burst-statistics\" data-category=\"statistics\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Burst Statistics pour website statistics. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/burst-statistics\/\">En savoir plus sur Burst Statistics<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistics (anonymous)<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/burst-statistics\/burst_uid\/\">burst_uid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">1 month<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Flow-Flow Social Stream<\/h3>\n\t\t<p>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/p>\n\t\t<label for=\"cmplz_service_flow-flow-social-stream\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service flow-flow-social-stream<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_flow-flow-social-stream\" class=\"cmplz-accept-service \" data-service=\"flow-flow-social-stream\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Flow-Flow Social Stream pour display of recent social posts and\/or social share buttons. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/flow-flow-social-stream\/\">En savoir plus sur Flow-Flow Social Stream<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Ces donn\u00e9es ne sont pas partag\u00e9es avec des tierces parties.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/flow-flow-social-stream\/ff_news_session\/\">ff_news_session<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Maps<\/h3>\n\t\t<p>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/p>\n\t\t<label for=\"cmplz_service_google-maps\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-maps<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-maps\" class=\"cmplz-accept-service \" data-service=\"google-maps\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Google Maps pour maps display. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-maps\/\">En savoir plus sur Google Maps<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">d\u00e9claration de confidentialit\u00e9 Google Maps<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">Google Maps API<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Fonts<\/h3>\n\t\t<p>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service \" data-service=\"google-fonts\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Google Fonts pour display of webfonts. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-fonts\/\">En savoir plus sur Google Fonts<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">d\u00e9claration de confidentialit\u00e9 Google Fonts<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">Google Fonts API<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Facebook<\/h3>\n\t\t<p>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/p>\n\t\t<label for=\"cmplz_service_facebook\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service facebook<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_facebook\" class=\"cmplz-accept-service \" data-service=\"facebook\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Facebook pour display of recent social posts and\/or social share buttons. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/facebook\/\">En savoir plus sur Facebook<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.facebook.com\/policy\/cookies\">d\u00e9claration de confidentialit\u00e9 Facebook<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_js_datr<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_fbc<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">fbm*<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">xs<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wd<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">fr<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">act<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_fbp<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">datr<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">c_user<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">csm<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">sb<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">actppresence<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">*_fbm_<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Vimeo<\/h3>\n\t\t<p>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/p>\n\t\t<label for=\"cmplz_service_vimeo\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service vimeo<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_vimeo\" class=\"cmplz-accept-service \" data-service=\"vimeo\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Vimeo pour video display. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/vimeo\/\">En savoir plus sur Vimeo<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/vimeo.com\/privacy\">d\u00e9claration de confidentialit\u00e9 Vimeo<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">__utmt_player<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">vuid<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>YouTube<\/h3>\n\t\t<p>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/p>\n\t\t<label for=\"cmplz_service_youtube\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service youtube<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_youtube\" class=\"cmplz-accept-service \" data-service=\"youtube\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons YouTube pour video display. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/youtube\/\">En savoir plus sur YouTube<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">d\u00e9claration de confidentialit\u00e9 YouTube<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">GPS<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">VISITOR_INFO1_LIVE<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">YSC<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">PREF<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Twitter<\/h3>\n\t\t<p>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/p>\n\t\t<label for=\"cmplz_service_twitter\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service twitter<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_twitter\" class=\"cmplz-accept-service \" data-service=\"twitter\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons Twitter pour display of recent social posts and\/or social share buttons. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/twitter\/\">En savoir plus sur Twitter<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/twitter.com\/en\/privacy\">d\u00e9claration de confidentialit\u00e9 Twitter<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">local_storage_support_test<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">metrics_token<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>LinkedIn<\/h3>\n\t\t<p>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/p>\n\t\t<label for=\"cmplz_service_linkedin\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service linkedin<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_linkedin\" class=\"cmplz-accept-service \" data-service=\"linkedin\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p>Nous utilisons LinkedIn pour display of recent social posts and\/or social share buttons. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/linkedin\/\">En savoir plus sur LinkedIn<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Pour plus d\u2019informations, veuillez lire la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\">d\u00e9claration de confidentialit\u00e9 LinkedIn<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">sdsc<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">lms_ads<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">lms_analytics<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_guid<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">li_alerts<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">li_gc<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">AnalyticsSyncHistory<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">bcookie<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">li-oatml<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">BizographicsOptOut<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">li_sugr<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">UserMatchHistory<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">linkedin_oauth_<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">lidc<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">bscookie<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">X-LI-IDC<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Divers<\/h3>\n\t\t<p>Functional<\/p>\n\t\t<label for=\"cmplz_service_divers\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service divers<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_divers\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"divers\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utilisation<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partage de donn\u00e9es<\/h4>\n\t\t<p>Le partage des donn\u00e9es est en cours d\u2019enqu\u00eate<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalit\u00e9 en attente d\u2019enqu\u00eate<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">continueReview<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">WP_DATA_USER_3<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbUrl-F5c25<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ate_widget_fetch_time<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wpformsChallengeStep<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">tpgb-Global-SetSettings<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbTime-Fd021<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbTime-F5c25<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbData-Fd021<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbData-F5c25<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbData-F2cab<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbTime-F2cab<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbUrl-Fd021<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbsetTime-F2cab<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbsetTime-Fd021<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ate_widget_url<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbsetTime-F5c25<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbUrl-F2cab<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ff_first_time<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ff_news<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbsetTime-Ff425<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbTime-Ff425<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbUrl-Ff901<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbData-Ff425<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbTime-Ff901<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbUrl-Ff425<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbData-Ff901<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbsetTime-Ff901<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wpml-job-list-collapsed<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">WP_DATA_USER_2<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbUrl-F054d<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbData-hamz<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbUrl-hamz<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbsetTime-F054d<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbData-F054d<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbTime-hamz<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbsetTime-hamz<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">FbTime-F054d<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">bis_data<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ff_notice_dismissed<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">WP_DATA_USER_4<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wpml-item-section-expanded<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">WP_DATA_USER_7<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wpml-available-translators-notice-dismissed<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wpml-last-picked-up-translation-methods<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ate-maiya-info_6c83677f-47b6-49af-8b16-d78560d31d6d<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">seopress_beacon_position<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wpml-translation-status-filter<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">e_globals<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">tusSupport<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ssPanelLeft<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">e_kit-elements-defaults<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ssPanelTop<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">customizerVisitCount<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ssPanelHeight<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ate-maiya-info<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">elementor<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">burst-tasks-storage<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ams_tq_last_ids<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ate-maiya-info_37353763-3331-5464-b338-663337333866<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">burst-insights-storage<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">currentStep<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">whats-new-cache-expiry-bmV3L2ZlZWQv<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">whats-new-cache-bmV3L2ZlZWQv<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">tpgbsetState<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">hfeSelectedItemId<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wp-postpass_0399cd1353c93e367b7bacdbd46844b8<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">e_my_templates_source<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_ams_session<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">mp_150605b3b9f979922f2ac5a52e2dcfe9_mixpanel<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">mp_gen_new_tab_id_mixpanel_150605b3b9f979922f2ac5a52e2dcfe9<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">mp_tab_id_mixpanel_150605b3b9f979922f2ac5a52e2dcfe9<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">adobeCleanFontAdded<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">__mp_opt_in_out_150605b3b9f979922f2ac5a52e2dcfe9<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wpcode_scroll_position<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">llar_login_flow<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wfwaf-authcookie-0b27039fc38b6f838192c98673d68028<\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/fblo_673060522871555\/\">fblo_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Expiration<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fonction<\/h5>\n<\/div>\n<div class=\"function\">M\u00e9moriser les utilisateurs connect\u00e9s<\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consentement<\/h2><p>Lorsque vous visitez notre site web pour la premi\u00e8re fois, nous vous montrerons une fen\u00eatre contextuelle avec une explication sur les cookies. D\u00e8s que vous cliquez sur \u00ab\u00a0Sauvegarder les pr\u00e9f\u00e9rences\u00a0\u00bb vous nous autorisez \u00e0 utiliser les cat\u00e9gories de cookies et d\u2019extensions que vous avez s\u00e9lectionn\u00e9s dans la fen\u00eatre contextuelle, comme d\u00e9crit dans la pr\u00e9sente politique de cookies. Vous pouvez d\u00e9sactiver l\u2019utilisation des cookies via votre navigateur, mais veuillez noter que notre site web pourrait ne plus fonctionner correctement.<\/p><h3>7.1 G\u00e9rez vos r\u00e9glages de consentement<\/h3><div id=\"cmplz-manage-consent-container-nojavascript\">Vous avez charg\u00e9 la politique de cookies sans le support de javascript.&nbsp;Sur AMP, vous pouvez utiliser l\u2019onglet de gestion du consentement en bas de la page.<\/div><div id=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Activer\/d\u00e9sactiver et supprimer les cookies<\/h2><p>Vous pouvez utiliser votre navigateur internet pour supprimer automatiquement ou manuellement les cookies. Vous pouvez \u00e9galement sp\u00e9cifier que certains cookies ne peuvent pas \u00eatre plac\u00e9s. Une autre option consiste \u00e0 modifier les r\u00e9glages de votre navigateur Internet afin que vous receviez un message \u00e0 chaque fois qu\u2019un cookie est plac\u00e9. Pour plus d\u2019informations sur ces options, reportez-vous aux instructions de la section Aide de votre navigateur.<\/p><p>Veuillez noter que notre site web peut ne pas marcher correctement si tous les cookies sont d\u00e9sactiv\u00e9s. Si vous supprimez les cookies dans votre navigateur, ils seront de nouveau plac\u00e9s apr\u00e8s votre consentement lorsque vous revisiterez notre site web.<\/p><h2>9. Vos droits concernant les donn\u00e9es personnelles<\/h2><p>Vous avez les droits suivants concernant vos donn\u00e9es personnelles\u00a0:<\/p><ul>\n                    <li>Vous avez le droit de savoir pourquoi vos donn\u00e9es personnelles sont n\u00e9cessaires, ce qui leur arrivera et combien de temps elles seront conserv\u00e9es.<\/li>\n                    <li>Droit d\u2019acc\u00e8s\u00a0: vous avez le droit d\u2019acc\u00e9der \u00e0 vos donn\u00e9es personnelles que nous connaissons.<\/li>\n                    <li>Droit de rectification\u00a0: vous avez le droit \u00e0 tout moment de compl\u00e9ter, corriger, faire supprimer ou bloquer vos donn\u00e9es personnelles.<\/li>\n                    <li>Si vous nous donnez votre consentement pour le traitement de vos donn\u00e9es, vous avez le droit de r\u00e9voquer ce consentement et de faire supprimer vos donn\u00e9es personnelles.<\/li>\n                    <li>Droit de transf\u00e9rer vos donn\u00e9es\u00a0: vous avez le droit de demander toutes vos donn\u00e9es personnelles au responsable du traitement et de les transf\u00e9rer dans leur int\u00e9gralit\u00e9 \u00e0 un autre responsable du traitement.<\/li>\n                    <li>Droit d\u2019opposition\u00a0: vous pouvez vous opposer au traitement de vos donn\u00e9es. Nous obtemp\u00e9rerons, \u00e0 moins que certaines raisons ne justifient ce traitement.<\/li>\n                <\/ul><p>Pour exercer ces droits, veuillez nous contacter. Veuillez vous r\u00e9f\u00e9rer aux coordonn\u00e9es au bas de cette politique de cookies. Si vous avez une plainte concernant la fa\u00e7on dont nous traitons vos donn\u00e9es, nous aimerions en \u00eatre inform\u00e9s, mais vous avez \u00e9galement le droit de d\u00e9poser une plainte aupr\u00e8s de l\u2019autorit\u00e9 de contr\u00f4le (l\u2019autorit\u00e9 charg\u00e9e de la protection des donn\u00e9es).<\/p><h2>10. Coordonn\u00e9es<\/h2><p>Pour des questions et\/ou des commentaires sur notre politique de cookies et cette d\u00e9claration, veuillez nous contacter en utilisant les coordonn\u00e9es suivantes\u00a0:<\/p><p><span class=\"cmplz-contact-organisation\">Arctic Boats Oy<\/span><br>\n                      <span class=\"cmplz-contact-address\">Neitsytpolku 3C 35<br \/>\n00140 Helsinki<br \/>\nFinland<\/span><br>\n                      <span class=\"cmplz-contact-country\">Finlande<\/span><br>\n                      <span class=\"cmplz-contact-domain\">Site web\u00a0: <a href=\"https:\/\/arcticboats.eu\/fr\/\">https:\/\/arcticboats.eu\/fr\/<\/a><\/span><br>\n                      <span class=\"cmplz-contact-email\">E-mail\u00a0: <span class=\"cmplz-obfuscate\">in&#102;&#111;@<span class=\"cmplz-fmail-domain\">&#101;&#120;&#046;c&#111;m<\/span>&#097;&#114;&#099;&#116;i&#099;&#098;oa&#116;s&#046;&#101;&#117;<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\">Num\u00e9ro de t\u00e9l\u00e9phone : +358 40 043 1025<\/span><\/p><p>Cette politique de cookies a \u00e9t\u00e9 synchronis\u00e9e avec <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">cookiedatabase.org<\/a> le 22 juillet 2025.<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":9000,"comment_status":"closed","ping_status":"closed","template":"elementor_theme","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"yes","_seopress_robots_follow":"yes","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","footnotes":""},"class_list":["post-13002","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/arcticboats.eu\/fr\/wp-json\/wp\/v2\/pages\/13002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arcticboats.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/arcticboats.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/arcticboats.eu\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/arcticboats.eu\/fr\/wp-json\/wp\/v2\/comments?post=13002"}],"version-history":[{"count":0,"href":"https:\/\/arcticboats.eu\/fr\/wp-json\/wp\/v2\/pages\/13002\/revisions"}],"wp:attachment":[{"href":"https:\/\/arcticboats.eu\/fr\/wp-json\/wp\/v2\/media?parent=13002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}